{"id":3352,"date":"2026-03-16T06:41:07","date_gmt":"2026-03-16T06:41:07","guid":{"rendered":"https:\/\/mtcc.com.my\/?page_id=3352"},"modified":"2026-07-01T10:35:28","modified_gmt":"2026-07-01T10:35:28","slug":"as-a-business-organisation","status":"publish","type":"page","link":"https:\/\/mtcc.com.my\/bm\/as-a-business-organisation\/","title":{"rendered":"As a Business Organisation"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"3352\" class=\"elementor elementor-3352\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c052bf8 e-flex e-con-boxed e-con e-parent\" data-id=\"c052bf8\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f250c02 e-con-full e-flex e-con e-child\" data-id=\"f250c02\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-e4b17fa e-con-full e-flex e-con e-child\" data-id=\"e4b17fa\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-66a1221 elementor-widget elementor-widget-heading\" data-id=\"66a1221\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">As a<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58d8d38 elementor-widget elementor-widget-heading\" data-id=\"58d8d38\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Business Organisation<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-68efb86 e-con-full e-flex e-con e-child\" data-id=\"68efb86\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-370a69e elementor-widget elementor-widget-text-editor\" data-id=\"370a69e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Access the standards, tools, and information needed by forest managers, auditors, and certification stakeholders involved in the MTCS.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-957d60c e-flex e-con-boxed e-con e-parent\" data-id=\"957d60c\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d124582 e-con-full e-flex e-con e-child\" data-id=\"d124582\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-47cfaf5 elementor-widget elementor-widget-heading\" data-id=\"47cfaf5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">As A<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b793927 elementor-widget elementor-widget-heading\" data-id=\"b793927\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Business Organisation<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9aacbf5 e-con-full e-flex e-con e-child\" data-id=\"9aacbf5\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-795133c e-con-full e-flex e-con e-child\" data-id=\"795133c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d7dcf3 elementor-widget elementor-widget-ucaddon_square_icon_box\" data-id=\"1d7dcf3\" data-element_type=\"widget\" data-widget_type=\"ucaddon_square_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Icon Box -->\n\t\t<link id='font-awesome-css' href='https:\/\/mtcc.com.my\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome6\/fontawesome-all.min.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='font-awesome-4-shim-css' href='https:\/\/mtcc.com.my\/wp-content\/plugins\/unlimited-elements-for-elementor-premium\/assets_libraries\/font-awesome6\/fontawesome-v4-shims.min.css' type='text\/css' rel='stylesheet' >\n\n<style>\/* widget: Icon Box *\/\n\n#uc_square_icon_box_elementor_1d7dcf3 * { \n\tbox-sizing: border-box; \n}\n\n#uc_square_icon_box_elementor_1d7dcf3{\n  font-family: inherit;\n  position:relative;\n}\n#uc_square_icon_box_elementor_1d7dcf3 svg{\n  width:1em;\n  height:1em;\n}\n\n#uc_square_icon_box_elementor_1d7dcf3 .blox-boxed-small-square-icon-box-icon{\n\tposition:relative;\n    display:flex;\n    justify-content:center;\n    align-items:center;\n    transform:rotate(0deg);\n    z-index:2;\n}\n#uc_square_icon_box_elementor_1d7dcf3 .ue-icon {\n  display:inline-block;\n}\n#uc_square_icon_box_elementor_1d7dcf3 .blox-boxed-small-square-icon-box-icon > div{\n\tposition:relative;\n    display:flex;\n    justify-content:center;\n    align-items:center;\n}\n#uc_square_icon_box_elementor_1d7dcf3 .ue-icon-inner{\n    line-height:1em;\n\t} \t\n\n\n#uc_square_icon_box_elementor_1d7dcf3 .ue-icon-inner svg{\n    height:1em;\n    width:1em;\n\t} \t\n\t\n.blox-boxed-small-square-icon-box-heading{\n\tfont-size:21px;\n\t}\n\n\n#uc_square_icon_box_elementor_1d7dcf3:hover\n{\n  position:relative;\n  z-index:1;\n}\n\n\n#uc_square_icon_box_elementor_1d7dcf3 .ue-title-separator span\n{\n  display:inline-block;\n}\n\n\n\n\n<\/style>\n\n<div class=\"square_icon_box\" id=\"uc_square_icon_box_elementor_1d7dcf3\">\n  \n  \t   <div class=\"ue-icon-title-wrap\">\n                  <div class=\"ue-icon-wrap\">\n           <div class=\"ue-icon\">\n                            <div class=\"blox-boxed-small-square-icon-box-icon\">\n                 <div class=\"ue-icon-inner\"><i class='fas fa-building'><\/i><\/div>\n               <\/div>\n                        <\/div>\n         <\/div>\n         \n                    <div  class=\"blox-boxed-small-square-icon-box-heading\">Industries and Businesses<\/div>\n                <\/div>\n  \n  \t\t  \n  \n                  <div class=\"blox-boxed-small-square-icon-box-content\">\n            <p>Industries and businesses involved in producing, processing, trading, or using timber products, seeking certification to demonstrate responsible sourcing and sustainability compliance.<\/p>\n          <\/div>\n          \n  \t\t        \n          \n  \t\t\n  \t\t  \n<\/div>\n<!-- end Icon Box -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-624f4d2 e-con-full e-flex e-con e-child\" data-id=\"624f4d2\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-643f366 e-grid e-con-full e-con e-child\" data-id=\"643f366\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f55354f elementor-widget elementor-widget-ucaddon_square_icon_box\" data-id=\"f55354f\" data-element_type=\"widget\" data-widget_type=\"ucaddon_square_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Icon Box -->\n\n<style>\/* widget: Icon Box *\/\n\n#uc_square_icon_box_elementor_f55354f * { \n\tbox-sizing: border-box; \n}\n\n#uc_square_icon_box_elementor_f55354f{\n  font-family: inherit;\n  position:relative;\n}\n#uc_square_icon_box_elementor_f55354f svg{\n  width:1em;\n  height:1em;\n}\n\n#uc_square_icon_box_elementor_f55354f .blox-boxed-small-square-icon-box-icon{\n\tposition:relative;\n    display:flex;\n    justify-content:center;\n    align-items:center;\n    transform:rotate(0deg);\n    z-index:2;\n}\n#uc_square_icon_box_elementor_f55354f .ue-icon {\n  display:inline-block;\n}\n#uc_square_icon_box_elementor_f55354f .blox-boxed-small-square-icon-box-icon > div{\n\tposition:relative;\n    display:flex;\n    justify-content:center;\n    align-items:center;\n}\n#uc_square_icon_box_elementor_f55354f .ue-icon-inner{\n    line-height:1em;\n\t} \t\n\n\n#uc_square_icon_box_elementor_f55354f .ue-icon-inner svg{\n    height:1em;\n    width:1em;\n\t} \t\n\t\n.blox-boxed-small-square-icon-box-heading{\n\tfont-size:21px;\n\t}\n\n\n#uc_square_icon_box_elementor_f55354f:hover\n{\n  position:relative;\n  z-index:1;\n}\n\n\n#uc_square_icon_box_elementor_f55354f .ue-title-separator span\n{\n  display:inline-block;\n}\n\n\n\n\n<\/style>\n\n<div class=\"square_icon_box\" id=\"uc_square_icon_box_elementor_f55354f\">\n  \n  \t   <div class=\"ue-icon-title-wrap\">\n                  <div class=\"ue-icon-wrap\">\n           <div class=\"ue-icon\">\n                            <div class=\"blox-boxed-small-square-icon-box-icon\">\n                 <div class=\"ue-icon-inner\"><i class='fas fa-check'><\/i><\/div>\n               <\/div>\n                        <\/div>\n         <\/div>\n         \n                    <div  class=\"blox-boxed-small-square-icon-box-heading\">How to Get Certified<\/div>\n                <\/div>\n  \n  \t\t  \n  \n                  <div class=\"blox-boxed-small-square-icon-box-content\">\n            <p>Learn the process, requirements, and steps to apply for certification under the Malaysian Timber Certification Scheme (MTCS).<\/p>\n          <\/div>\n          \n  \t\t        \n          \n  \t\t\n  \t\t  \n<\/div>\n<!-- end Icon Box -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c3e3ec1 elementor-widget elementor-widget-ucaddon_square_icon_box\" data-id=\"c3e3ec1\" data-element_type=\"widget\" data-widget_type=\"ucaddon_square_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Icon Box -->\n\n<style>\/* widget: Icon Box *\/\n\n#uc_square_icon_box_elementor_c3e3ec1 * { \n\tbox-sizing: border-box; \n}\n\n#uc_square_icon_box_elementor_c3e3ec1{\n  font-family: inherit;\n  position:relative;\n}\n#uc_square_icon_box_elementor_c3e3ec1 svg{\n  width:1em;\n  height:1em;\n}\n\n#uc_square_icon_box_elementor_c3e3ec1 .blox-boxed-small-square-icon-box-icon{\n\tposition:relative;\n    display:flex;\n    justify-content:center;\n    align-items:center;\n    transform:rotate(0deg);\n    z-index:2;\n}\n#uc_square_icon_box_elementor_c3e3ec1 .ue-icon {\n  display:inline-block;\n}\n#uc_square_icon_box_elementor_c3e3ec1 .blox-boxed-small-square-icon-box-icon > div{\n\tposition:relative;\n    display:flex;\n    justify-content:center;\n    align-items:center;\n}\n#uc_square_icon_box_elementor_c3e3ec1 .ue-icon-inner{\n    line-height:1em;\n\t} \t\n\n\n#uc_square_icon_box_elementor_c3e3ec1 .ue-icon-inner svg{\n    height:1em;\n    width:1em;\n\t} \t\n\t\n.blox-boxed-small-square-icon-box-heading{\n\tfont-size:21px;\n\t}\n\n\n#uc_square_icon_box_elementor_c3e3ec1:hover\n{\n  position:relative;\n  z-index:1;\n}\n\n\n#uc_square_icon_box_elementor_c3e3ec1 .ue-title-separator span\n{\n  display:inline-block;\n}\n\n\n\n\n<\/style>\n\n<div class=\"square_icon_box\" id=\"uc_square_icon_box_elementor_c3e3ec1\">\n  \n  \t   <div class=\"ue-icon-title-wrap\">\n                  <div class=\"ue-icon-wrap\">\n           <div class=\"ue-icon\">\n                            <div class=\"blox-boxed-small-square-icon-box-icon\">\n                 <div class=\"ue-icon-inner\"><i class='fas fa-check'><\/i><\/div>\n               <\/div>\n                        <\/div>\n         <\/div>\n         \n                    <div  class=\"blox-boxed-small-square-icon-box-heading\"> About MTCS Certification<\/div>\n                <\/div>\n  \n  \t\t  \n  \n                  <div class=\"blox-boxed-small-square-icon-box-content\">\n            <p>Understand the structure, scope, and requirements of MTCS, including the standards and technical documents that support certification and ongoing compliance.<\/p>\n          <\/div>\n          \n  \t\t        \n          \n  \t\t\n  \t\t  \n<\/div>\n<!-- end Icon Box -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7b3b65 elementor-widget elementor-widget-ucaddon_square_icon_box\" data-id=\"a7b3b65\" data-element_type=\"widget\" data-widget_type=\"ucaddon_square_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Icon Box -->\n\n<style>\/* widget: Icon Box *\/\n\n#uc_square_icon_box_elementor_a7b3b65 * { \n\tbox-sizing: border-box; \n}\n\n#uc_square_icon_box_elementor_a7b3b65{\n  font-family: inherit;\n  position:relative;\n}\n#uc_square_icon_box_elementor_a7b3b65 svg{\n  width:1em;\n  height:1em;\n}\n\n#uc_square_icon_box_elementor_a7b3b65 .blox-boxed-small-square-icon-box-icon{\n\tposition:relative;\n    display:flex;\n    justify-content:center;\n    align-items:center;\n    transform:rotate(0deg);\n    z-index:2;\n}\n#uc_square_icon_box_elementor_a7b3b65 .ue-icon {\n  display:inline-block;\n}\n#uc_square_icon_box_elementor_a7b3b65 .blox-boxed-small-square-icon-box-icon > div{\n\tposition:relative;\n    display:flex;\n    justify-content:center;\n    align-items:center;\n}\n#uc_square_icon_box_elementor_a7b3b65 .ue-icon-inner{\n    line-height:1em;\n\t} \t\n\n\n#uc_square_icon_box_elementor_a7b3b65 .ue-icon-inner svg{\n    height:1em;\n    width:1em;\n\t} \t\n\t\n.blox-boxed-small-square-icon-box-heading{\n\tfont-size:21px;\n\t}\n\n\n#uc_square_icon_box_elementor_a7b3b65:hover\n{\n  position:relative;\n  z-index:1;\n}\n\n\n#uc_square_icon_box_elementor_a7b3b65 .ue-title-separator span\n{\n  display:inline-block;\n}\n\n\n  #uc_square_icon_box_elementor_a7b3b65 .ue_box_link_overlay{\n    position:absolute;\n    display:block;\n    top:0;\n    bottom:0; \n    right:0;\n    left:0;\n  }\n\n\n<\/style>\n\n<div class=\"square_icon_box\" id=\"uc_square_icon_box_elementor_a7b3b65\">\n  \n  \t   <div class=\"ue-icon-title-wrap\">\n                  <div class=\"ue-icon-wrap\">\n           <div class=\"ue-icon\">\n             <a style=\"display:inline-block; text-decoration:none;\" href=\"\/bm\/normative-documents\/\" >               <div class=\"blox-boxed-small-square-icon-box-icon\">\n                 <div class=\"ue-icon-inner\"><i class='fas fa-check'><\/i><\/div>\n               <\/div>\n             <\/a>           <\/div>\n         <\/div>\n         \n                    <div  class=\"blox-boxed-small-square-icon-box-heading\">Download Technical Documents<\/div>\n                <\/div>\n  \n  \t\t  \n  \n                  <div class=\"blox-boxed-small-square-icon-box-content\">\n            <p>Access supporting technical documents, procedures, and guidance to help implement <br \/>and maintain certification <br \/>requirements.<\/p>\n          <\/div>\n          \n  \t\t        \n          \n  \t\t  \t\t<a href=\"\/bm\/normative-documents\/\" class=\"ue_box_link_overlay\" > <\/a>\n        \n  \t\t  \n<\/div>\n<!-- end Icon Box -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-70d48fc elementor-widget elementor-widget-ucaddon_square_icon_box\" data-id=\"70d48fc\" data-element_type=\"widget\" data-widget_type=\"ucaddon_square_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Icon Box -->\n\n<style>\/* widget: Icon Box *\/\n\n#uc_square_icon_box_elementor_70d48fc * { \n\tbox-sizing: border-box; \n}\n\n#uc_square_icon_box_elementor_70d48fc{\n  font-family: inherit;\n  position:relative;\n}\n#uc_square_icon_box_elementor_70d48fc svg{\n  width:1em;\n  height:1em;\n}\n\n#uc_square_icon_box_elementor_70d48fc .blox-boxed-small-square-icon-box-icon{\n\tposition:relative;\n    display:flex;\n    justify-content:center;\n    align-items:center;\n    transform:rotate(0deg);\n    z-index:2;\n}\n#uc_square_icon_box_elementor_70d48fc .ue-icon {\n  display:inline-block;\n}\n#uc_square_icon_box_elementor_70d48fc .blox-boxed-small-square-icon-box-icon > div{\n\tposition:relative;\n    display:flex;\n    justify-content:center;\n    align-items:center;\n}\n#uc_square_icon_box_elementor_70d48fc .ue-icon-inner{\n    line-height:1em;\n\t} \t\n\n\n#uc_square_icon_box_elementor_70d48fc .ue-icon-inner svg{\n    height:1em;\n    width:1em;\n\t} \t\n\t\n.blox-boxed-small-square-icon-box-heading{\n\tfont-size:21px;\n\t}\n\n\n#uc_square_icon_box_elementor_70d48fc:hover\n{\n  position:relative;\n  z-index:1;\n}\n\n\n#uc_square_icon_box_elementor_70d48fc .ue-title-separator span\n{\n  display:inline-block;\n}\n\n\n  #uc_square_icon_box_elementor_70d48fc .ue_box_link_overlay{\n    position:absolute;\n    display:block;\n    top:0;\n    bottom:0; \n    right:0;\n    left:0;\n  }\n\n\n<\/style>\n\n<div class=\"square_icon_box\" id=\"uc_square_icon_box_elementor_70d48fc\">\n  \n  \t   <div class=\"ue-icon-title-wrap\">\n                  <div class=\"ue-icon-wrap\">\n           <div class=\"ue-icon\">\n             <a style=\"display:inline-block; text-decoration:none;\" href=\"\/bm\/certified-forests-in-malaysia\/\" >               <div class=\"blox-boxed-small-square-icon-box-icon\">\n                 <div class=\"ue-icon-inner\"><i class='fas fa-check'><\/i><\/div>\n               <\/div>\n             <\/a>           <\/div>\n         <\/div>\n         \n                    <div  class=\"blox-boxed-small-square-icon-box-heading\">Get Statistics of Certified Areas<\/div>\n                <\/div>\n  \n  \t\t  \n  \n                  <div class=\"blox-boxed-small-square-icon-box-content\">\n            <p>View certification data, including certified companies and forest areas, through the statistics dashboard and interactive forest map.<\/p>\n          <\/div>\n          \n  \t\t        \n          \n  \t\t  \t\t<a href=\"\/bm\/certified-forests-in-malaysia\/\" class=\"ue_box_link_overlay\" > <\/a>\n        \n  \t\t  \n<\/div>\n<!-- end Icon Box -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17318a8 elementor-widget elementor-widget-ucaddon_square_icon_box\" data-id=\"17318a8\" data-element_type=\"widget\" data-widget_type=\"ucaddon_square_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Icon Box -->\n\n<style>\/* widget: Icon Box *\/\n\n#uc_square_icon_box_elementor_17318a8 * { \n\tbox-sizing: border-box; \n}\n\n#uc_square_icon_box_elementor_17318a8{\n  font-family: inherit;\n  position:relative;\n}\n#uc_square_icon_box_elementor_17318a8 svg{\n  width:1em;\n  height:1em;\n}\n\n#uc_square_icon_box_elementor_17318a8 .blox-boxed-small-square-icon-box-icon{\n\tposition:relative;\n    display:flex;\n    justify-content:center;\n    align-items:center;\n    transform:rotate(0deg);\n    z-index:2;\n}\n#uc_square_icon_box_elementor_17318a8 .ue-icon {\n  display:inline-block;\n}\n#uc_square_icon_box_elementor_17318a8 .blox-boxed-small-square-icon-box-icon > div{\n\tposition:relative;\n    display:flex;\n    justify-content:center;\n    align-items:center;\n}\n#uc_square_icon_box_elementor_17318a8 .ue-icon-inner{\n    line-height:1em;\n\t} \t\n\n\n#uc_square_icon_box_elementor_17318a8 .ue-icon-inner svg{\n    height:1em;\n    width:1em;\n\t} \t\n\t\n.blox-boxed-small-square-icon-box-heading{\n\tfont-size:21px;\n\t}\n\n\n#uc_square_icon_box_elementor_17318a8:hover\n{\n  position:relative;\n  z-index:1;\n}\n\n\n#uc_square_icon_box_elementor_17318a8 .ue-title-separator span\n{\n  display:inline-block;\n}\n\n\n  #uc_square_icon_box_elementor_17318a8 .ue_box_link_overlay{\n    position:absolute;\n    display:block;\n    top:0;\n    bottom:0; \n    right:0;\n    left:0;\n  }\n\n\n<\/style>\n\n<div class=\"square_icon_box\" id=\"uc_square_icon_box_elementor_17318a8\">\n  \n  \t   <div class=\"ue-icon-title-wrap\">\n                  <div class=\"ue-icon-wrap\">\n           <div class=\"ue-icon\">\n             <a style=\"display:inline-block; text-decoration:none;\" href=\"\/bm\/find-certified-companies\/\" >               <div class=\"blox-boxed-small-square-icon-box-icon\">\n                 <div class=\"ue-icon-inner\"><i class='fas fa-check'><\/i><\/div>\n               <\/div>\n             <\/a>           <\/div>\n         <\/div>\n         \n                    <div  class=\"blox-boxed-small-square-icon-box-heading\">Find Certified Companies and Products<\/div>\n                <\/div>\n  \n  \t\t  \n  \n                  <div class=\"blox-boxed-small-square-icon-box-content\">\n            <p>Search and verify certified suppliers and products to ensure they meet recognised MTCS and PEFC certification standards.<\/p>\n          <\/div>\n          \n  \t\t        \n          \n  \t\t  \t\t<a href=\"\/bm\/find-certified-companies\/\" class=\"ue_box_link_overlay\" > <\/a>\n        \n  \t\t  \n<\/div>\n<!-- end Icon Box -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af82b53 elementor-widget elementor-widget-ucaddon_square_icon_box\" data-id=\"af82b53\" data-element_type=\"widget\" data-widget_type=\"ucaddon_square_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Icon Box -->\n\n<style>\/* widget: Icon Box *\/\n\n#uc_square_icon_box_elementor_af82b53 * { \n\tbox-sizing: border-box; \n}\n\n#uc_square_icon_box_elementor_af82b53{\n  font-family: inherit;\n  position:relative;\n}\n#uc_square_icon_box_elementor_af82b53 svg{\n  width:1em;\n  height:1em;\n}\n\n#uc_square_icon_box_elementor_af82b53 .blox-boxed-small-square-icon-box-icon{\n\tposition:relative;\n    display:flex;\n    justify-content:center;\n    align-items:center;\n    transform:rotate(0deg);\n    z-index:2;\n}\n#uc_square_icon_box_elementor_af82b53 .ue-icon {\n  display:inline-block;\n}\n#uc_square_icon_box_elementor_af82b53 .blox-boxed-small-square-icon-box-icon > div{\n\tposition:relative;\n    display:flex;\n    justify-content:center;\n    align-items:center;\n}\n#uc_square_icon_box_elementor_af82b53 .ue-icon-inner{\n    line-height:1em;\n\t} \t\n\n\n#uc_square_icon_box_elementor_af82b53 .ue-icon-inner svg{\n    height:1em;\n    width:1em;\n\t} \t\n\t\n.blox-boxed-small-square-icon-box-heading{\n\tfont-size:21px;\n\t}\n\n\n#uc_square_icon_box_elementor_af82b53:hover\n{\n  position:relative;\n  z-index:1;\n}\n\n\n#uc_square_icon_box_elementor_af82b53 .ue-title-separator span\n{\n  display:inline-block;\n}\n\n\n\n\n<\/style>\n\n<div class=\"square_icon_box\" id=\"uc_square_icon_box_elementor_af82b53\">\n  \n  \t   <div class=\"ue-icon-title-wrap\">\n                  <div class=\"ue-icon-wrap\">\n           <div class=\"ue-icon\">\n                            <div class=\"blox-boxed-small-square-icon-box-icon\">\n                 <div class=\"ue-icon-inner\"><i class='fas fa-check'><\/i><\/div>\n               <\/div>\n                        <\/div>\n         <\/div>\n         \n                    <div  class=\"blox-boxed-small-square-icon-box-heading\">Certification Logos and Trademark Usage<\/div>\n                <\/div>\n  \n  \t\t  \n  \n                  <div class=\"blox-boxed-small-square-icon-box-content\">\n            <p>Download official MTCC and PEFC certification logos and <br \/>understand the proper requirements for using certification trademarks in marketing, packaging, and <br \/>communications.<\/p>\n          <\/div>\n          \n  \t\t        \n          \n  \t\t\n  \t\t  \n<\/div>\n<!-- end Icon Box -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6a79514 e-con-full e-flex e-con e-child\" data-id=\"6a79514\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-8ccdb51 e-con-full e-flex e-con e-child\" data-id=\"8ccdb51\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f487de6 elementor-widget elementor-widget-ucaddon_square_icon_box\" data-id=\"f487de6\" data-element_type=\"widget\" data-widget_type=\"ucaddon_square_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Icon Box -->\n\n<style>\/* widget: Icon Box *\/\n\n#uc_square_icon_box_elementor_f487de6 * { \n\tbox-sizing: border-box; \n}\n\n#uc_square_icon_box_elementor_f487de6{\n  font-family: inherit;\n  position:relative;\n}\n#uc_square_icon_box_elementor_f487de6 svg{\n  width:1em;\n  height:1em;\n}\n\n#uc_square_icon_box_elementor_f487de6 .blox-boxed-small-square-icon-box-icon{\n\tposition:relative;\n    display:flex;\n    justify-content:center;\n    align-items:center;\n    transform:rotate(0deg);\n    z-index:2;\n}\n#uc_square_icon_box_elementor_f487de6 .ue-icon {\n  display:inline-block;\n}\n#uc_square_icon_box_elementor_f487de6 .blox-boxed-small-square-icon-box-icon > div{\n\tposition:relative;\n    display:flex;\n    justify-content:center;\n    align-items:center;\n}\n#uc_square_icon_box_elementor_f487de6 .ue-icon-inner{\n    line-height:1em;\n\t} \t\n\n\n#uc_square_icon_box_elementor_f487de6 .ue-icon-inner svg{\n    height:1em;\n    width:1em;\n\t} \t\n\t\n.blox-boxed-small-square-icon-box-heading{\n\tfont-size:21px;\n\t}\n\n\n#uc_square_icon_box_elementor_f487de6:hover\n{\n  position:relative;\n  z-index:1;\n}\n\n\n#uc_square_icon_box_elementor_f487de6 .ue-title-separator span\n{\n  display:inline-block;\n}\n\n\n\n\n<\/style>\n\n<div class=\"square_icon_box\" id=\"uc_square_icon_box_elementor_f487de6\">\n  \n  \t   <div class=\"ue-icon-title-wrap\">\n                  <div class=\"ue-icon-wrap\">\n           <div class=\"ue-icon\">\n                            <div class=\"blox-boxed-small-square-icon-box-icon\">\n                 <div class=\"ue-icon-inner\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Layer_2\" data-name=\"Layer 2\" viewbox=\"0 0 32.76 43.36\"><defs><style>      .cls-1 {        fill: none;      }      .cls-1, .cls-2, .cls-3 {        stroke-width: 0px;      }      .cls-2 {        fill: #016255;      }      .cls-3 {        fill: #fff;      }    <\/style><\/defs><g id=\"Layer_1-2\" data-name=\"Layer 1\"><g><path class=\"cls-1\" d=\"M10.34,21.92c-.44.07-.79.44-.79.88v.71c0,.45.35.83.81.89-.04-.35-.07-.7-.07-1.06,0-.31.03-.61.06-.91,0-.17-.01-.34-.01-.51Z\"><\/path><path class=\"cls-1\" d=\"M26.95,21.06c-3.23-.24-12.09-2.31-12.09-2.31-.54.95-1.94,2.16-3.03,2.94-.04.17-.08.34-.11.51-.06.38-.1.76-.1,1.15,0,.28.02.55.05.82.05.46.15.91.28,1.35.98,3.18,4.04,5.5,7.65,5.5s6.67-2.33,7.65-5.5c.13-.43.23-.88.28-1.35.03-.27.05-.55.05-.82,0-.39-.04-.77-.1-1.14-.06-.39-.16-.76-.28-1.13-.08,0-.17,0-.26-.01Z\"><\/path><path class=\"cls-1\" d=\"M29.67,23.51v-.71c0-.42-.3-.76-.69-.86-.03.13-.08.25-.12.38.04.34.08.68.08,1.02s-.03.71-.07,1.06c.45-.06.81-.44.81-.89Z\"><\/path><path class=\"cls-1\" d=\"M7.66,6.38c-1.62,1-2.18,3.18-1.24,4.84,1,1.76,3.24,2.36,4.98,1.33,1.71-1.02,2.28-3.23,1.27-4.94-1.03-1.73-3.28-2.3-5.01-1.23Z\"><\/path><path class=\"cls-2\" d=\"M20.73,34.85l1.11,7.27h1.33l2.06-10.82c-.2-.02-.4-.03-.61-.03h-.66c-1.3.66-2.77,1.04-4.34,1.04s-3.05-.38-4.35-1.04h-.66c-.21,0-.41.02-.61.03l2.06,10.82h1.33l1.11-7.27h.04l-1.09-2h4.35l-1.09,2h.04Z\"><\/path><path class=\"cls-3\" d=\"M23.17,42.12h-7.12l-2.06-10.82c-4.21.31-7.53,3.82-7.53,8.1v3.95h26.29v-3.95c0-4.29-3.32-7.79-7.53-8.1l-2.06,10.82Z\"><\/path><polygon class=\"cls-3\" points=\"17.38 42.12 21.84 42.12 20.73 34.85 20.7 34.85 21.78 32.85 17.44 32.85 18.52 34.85 18.48 34.85 17.38 42.12\"><\/polygon><path class=\"cls-3\" d=\"M15.75,10.73c.12-.11.24-.21.34-.29.47-.35,1.93-.87,2.24-.89h0c.22,0,.46.14.75.39.02-.51,0-1.02-.06-1.52l-1.61-.38c-.08-.42-.2-.84-.36-1.25l1.18-1.16c-.14-.31-.3-.62-.48-.92-.18-.3-.37-.59-.58-.86l-1.59.47c-.29-.33-.6-.64-.93-.91l.44-1.6c-.57-.41-1.17-.75-1.81-1.02l-1.14,1.21c-.41-.14-.83-.25-1.26-.33l-.42-1.61c-.69-.07-1.38-.06-2.07.03l-.39,1.61c-.42.08-.84.2-1.25.35l-1.16-1.18c-.31.14-.62.3-.92.48-.3.18-.59.37-.86.58l.47,1.59c-.33.29-.64.6-.91.93l-1.6-.44c-.41.57-.75,1.17-1.02,1.8l1.21,1.14c-.14.41-.25.83-.32,1.26l-1.6.42c-.07.69-.06,1.38.02,2.07l1.61.38c.08.42.2.84.35,1.26l-1.18,1.16c.14.31.3.62.48.92.18.3.37.59.58.86l1.59-.47c.29.33.6.64.93.91l-.44,1.6c.57.4,1.17.75,1.8,1.02l1.14-1.2c.41.14.83.25,1.26.32l.42,1.61c.31.03.62.04.93.04v-.05c0-3.94,2.62-7.25,6.21-8.31ZM11.39,12.56c-1.74,1.03-3.98.43-4.98-1.33-.94-1.66-.38-3.84,1.24-4.84,1.72-1.07,3.98-.5,5.01,1.23,1.01,1.72.44,3.93-1.27,4.94Z\"><\/path><path class=\"cls-3\" d=\"M8.21,22.8v.71c0,1.21,1.02,2.2,2.28,2.2h.13c.69,2.41,2.39,4.41,4.64,5.56,1.3.66,2.78,1.04,4.35,1.04s3.05-.38,4.34-1.04c2.25-1.15,3.95-3.15,4.64-5.56h.13c1.26,0,2.28-.98,2.28-2.2v-.71c0-1.05-.77-1.93-1.8-2.14.04-.31.06-.64.06-.96v-.09c0-.23-.01-.47-.04-.73h0c-.14-1.5-.66-2.89-1.47-4.06-.42-.61-.91-1.16-1.46-1.64-1.48-1.29-3.39-2.09-5.49-2.14l-.11-.08c-.09-.1-.19-.12-.26-.12-.16,0-.27.1-.36.19h-.03c-.17-.17-.32-.31-.47-.43-.29-.25-.53-.39-.75-.39h0c-.31.02-1.77.54-2.24.89-.1.08-.22.18-.34.29-3.59,1.06-6.21,4.38-6.21,8.31v.05s0,.13,0,.13c0,.26,0,.53.03.78-1.07.18-1.88,1.07-1.88,2.14ZM28.98,21.94c.4.11.69.45.69.86v.71c0,.45-.35.83-.81.89.04-.35.07-.7.07-1.06s-.03-.69-.08-1.02c.04-.13.08-.25.12-.38ZM11.73,22.2c.03-.17.07-.34.11-.51,1.1-.78,2.5-1.99,3.03-2.94,0,0,8.86,2.08,12.09,2.31.09,0,.18,0,.26.01.12.37.21.74.28,1.13.06.37.1.76.1,1.14,0,.28-.02.55-.05.82-.05.46-.15.91-.28,1.35-.98,3.18-4.04,5.5-7.65,5.5s-6.68-2.33-7.65-5.5c-.13-.43-.23-.88-.28-1.35-.03-.27-.05-.55-.05-.82,0-.39.04-.77.1-1.15ZM9.55,22.8c0-.45.34-.81.79-.88,0,.17,0,.34.01.51-.04.3-.06.6-.06.91,0,.36.03.71.07,1.06-.46-.06-.81-.44-.81-.89v-.71Z\"><\/path><\/g><\/g><\/svg><\/div>\n               <\/div>\n                        <\/div>\n         <\/div>\n         \n                    <div  class=\"blox-boxed-small-square-icon-box-heading\">Specifiers and Procurement Professionals<\/div>\n                <\/div>\n  \n  \t\t  \n  \n                  <div class=\"blox-boxed-small-square-icon-box-content\">\n            <p>Specifiers and procurement professionals responsible for selecting materials and suppliers, ensuring timber products meet certification standards, sustainability requirements, and responsible sourcing policies.<\/p>\n          <\/div>\n          \n  \t\t        \n          \n  \t\t\n  \t\t  \n<\/div>\n<!-- end Icon Box -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3df296a e-con-full e-flex e-con e-child\" data-id=\"3df296a\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a27d416 e-grid e-con-full e-con e-child\" data-id=\"a27d416\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-574198f elementor-widget elementor-widget-ucaddon_square_icon_box\" data-id=\"574198f\" data-element_type=\"widget\" data-widget_type=\"ucaddon_square_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Icon Box -->\n\n<style>\/* widget: Icon Box *\/\n\n#uc_square_icon_box_elementor_574198f * { \n\tbox-sizing: border-box; \n}\n\n#uc_square_icon_box_elementor_574198f{\n  font-family: inherit;\n  position:relative;\n}\n#uc_square_icon_box_elementor_574198f svg{\n  width:1em;\n  height:1em;\n}\n\n#uc_square_icon_box_elementor_574198f .blox-boxed-small-square-icon-box-icon{\n\tposition:relative;\n    display:flex;\n    justify-content:center;\n    align-items:center;\n    transform:rotate(0deg);\n    z-index:2;\n}\n#uc_square_icon_box_elementor_574198f .ue-icon {\n  display:inline-block;\n}\n#uc_square_icon_box_elementor_574198f .blox-boxed-small-square-icon-box-icon > div{\n\tposition:relative;\n    display:flex;\n    justify-content:center;\n    align-items:center;\n}\n#uc_square_icon_box_elementor_574198f .ue-icon-inner{\n    line-height:1em;\n\t} \t\n\n\n#uc_square_icon_box_elementor_574198f .ue-icon-inner svg{\n    height:1em;\n    width:1em;\n\t} \t\n\t\n.blox-boxed-small-square-icon-box-heading{\n\tfont-size:21px;\n\t}\n\n\n#uc_square_icon_box_elementor_574198f:hover\n{\n  position:relative;\n  z-index:1;\n}\n\n\n#uc_square_icon_box_elementor_574198f .ue-title-separator span\n{\n  display:inline-block;\n}\n\n\n  #uc_square_icon_box_elementor_574198f .ue_box_link_overlay{\n    position:absolute;\n    display:block;\n    top:0;\n    bottom:0; \n    right:0;\n    left:0;\n  }\n\n\n<\/style>\n\n<div class=\"square_icon_box\" id=\"uc_square_icon_box_elementor_574198f\">\n  \n  \t   <div class=\"ue-icon-title-wrap\">\n                  <div class=\"ue-icon-wrap\">\n           <div class=\"ue-icon\">\n             <a style=\"display:inline-block; text-decoration:none;\" href=\"\/bm\/find-certified-companies\/\" >               <div class=\"blox-boxed-small-square-icon-box-icon\">\n                 <div class=\"ue-icon-inner\"><i class='fas fa-check'><\/i><\/div>\n               <\/div>\n             <\/a>           <\/div>\n         <\/div>\n         \n                    <div  class=\"blox-boxed-small-square-icon-box-heading\">Find Certified Companies and Products<\/div>\n                <\/div>\n  \n  \t\t  \n  \n                  <div class=\"blox-boxed-small-square-icon-box-content\">\n            <p>Search and verify suppliers certified under MTCS and PEFC, ensuring their certification is valid and aligned with responsible sourcing and procurement policies.<\/p>\n          <\/div>\n          \n  \t\t        \n          \n  \t\t  \t\t<a href=\"\/bm\/find-certified-companies\/\" class=\"ue_box_link_overlay\" > <\/a>\n        \n  \t\t  \n<\/div>\n<!-- end Icon Box -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c0c1a7 elementor-widget elementor-widget-ucaddon_square_icon_box\" data-id=\"2c0c1a7\" data-element_type=\"widget\" data-widget_type=\"ucaddon_square_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Icon Box -->\n\n<style>\/* widget: Icon Box *\/\n\n#uc_square_icon_box_elementor_2c0c1a7 * { \n\tbox-sizing: border-box; \n}\n\n#uc_square_icon_box_elementor_2c0c1a7{\n  font-family: inherit;\n  position:relative;\n}\n#uc_square_icon_box_elementor_2c0c1a7 svg{\n  width:1em;\n  height:1em;\n}\n\n#uc_square_icon_box_elementor_2c0c1a7 .blox-boxed-small-square-icon-box-icon{\n\tposition:relative;\n    display:flex;\n    justify-content:center;\n    align-items:center;\n    transform:rotate(0deg);\n    z-index:2;\n}\n#uc_square_icon_box_elementor_2c0c1a7 .ue-icon {\n  display:inline-block;\n}\n#uc_square_icon_box_elementor_2c0c1a7 .blox-boxed-small-square-icon-box-icon > div{\n\tposition:relative;\n    display:flex;\n    justify-content:center;\n    align-items:center;\n}\n#uc_square_icon_box_elementor_2c0c1a7 .ue-icon-inner{\n    line-height:1em;\n\t} \t\n\n\n#uc_square_icon_box_elementor_2c0c1a7 .ue-icon-inner svg{\n    height:1em;\n    width:1em;\n\t} \t\n\t\n.blox-boxed-small-square-icon-box-heading{\n\tfont-size:21px;\n\t}\n\n\n#uc_square_icon_box_elementor_2c0c1a7:hover\n{\n  position:relative;\n  z-index:1;\n}\n\n\n#uc_square_icon_box_elementor_2c0c1a7 .ue-title-separator span\n{\n  display:inline-block;\n}\n\n\n  #uc_square_icon_box_elementor_2c0c1a7 .ue_box_link_overlay{\n    position:absolute;\n    display:block;\n    top:0;\n    bottom:0; \n    right:0;\n    left:0;\n  }\n\n\n<\/style>\n\n<div class=\"square_icon_box\" id=\"uc_square_icon_box_elementor_2c0c1a7\">\n  \n  \t   <div class=\"ue-icon-title-wrap\">\n                  <div class=\"ue-icon-wrap\">\n           <div class=\"ue-icon\">\n             <a style=\"display:inline-block; text-decoration:none;\" href=\"\/bm\/normative-document\/\" >               <div class=\"blox-boxed-small-square-icon-box-icon\">\n                 <div class=\"ue-icon-inner\"><i class='fas fa-check'><\/i><\/div>\n               <\/div>\n             <\/a>           <\/div>\n         <\/div>\n         \n                    <div  class=\"blox-boxed-small-square-icon-box-heading\">Normative Documents<\/div>\n                <\/div>\n  \n  \t\t  \n  \n                  <div class=\"blox-boxed-small-square-icon-box-content\">\n            <p>Download MTCS standards, procedures, and technical documents that define certification requirements and ensure alignment with recognised sustainability frameworks.<\/p>\n          <\/div>\n          \n  \t\t        \n          \n  \t\t  \t\t<a href=\"\/bm\/normative-document\/\" class=\"ue_box_link_overlay\" > <\/a>\n        \n  \t\t  \n<\/div>\n<!-- end Icon Box -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-38db6be elementor-widget elementor-widget-ucaddon_square_icon_box\" data-id=\"38db6be\" data-element_type=\"widget\" data-widget_type=\"ucaddon_square_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Icon Box -->\n\n<style>\/* widget: Icon Box *\/\n\n#uc_square_icon_box_elementor_38db6be * { \n\tbox-sizing: border-box; \n}\n\n#uc_square_icon_box_elementor_38db6be{\n  font-family: inherit;\n  position:relative;\n}\n#uc_square_icon_box_elementor_38db6be svg{\n  width:1em;\n  height:1em;\n}\n\n#uc_square_icon_box_elementor_38db6be .blox-boxed-small-square-icon-box-icon{\n\tposition:relative;\n    display:flex;\n    justify-content:center;\n    align-items:center;\n    transform:rotate(0deg);\n    z-index:2;\n}\n#uc_square_icon_box_elementor_38db6be .ue-icon {\n  display:inline-block;\n}\n#uc_square_icon_box_elementor_38db6be .blox-boxed-small-square-icon-box-icon > div{\n\tposition:relative;\n    display:flex;\n    justify-content:center;\n    align-items:center;\n}\n#uc_square_icon_box_elementor_38db6be .ue-icon-inner{\n    line-height:1em;\n\t} \t\n\n\n#uc_square_icon_box_elementor_38db6be .ue-icon-inner svg{\n    height:1em;\n    width:1em;\n\t} \t\n\t\n.blox-boxed-small-square-icon-box-heading{\n\tfont-size:21px;\n\t}\n\n\n#uc_square_icon_box_elementor_38db6be:hover\n{\n  position:relative;\n  z-index:1;\n}\n\n\n#uc_square_icon_box_elementor_38db6be .ue-title-separator span\n{\n  display:inline-block;\n}\n\n\n\n\n<\/style>\n\n<div class=\"square_icon_box\" id=\"uc_square_icon_box_elementor_38db6be\">\n  \n  \t   <div class=\"ue-icon-title-wrap\">\n                  <div class=\"ue-icon-wrap\">\n           <div class=\"ue-icon\">\n                            <div class=\"blox-boxed-small-square-icon-box-icon\">\n                 <div class=\"ue-icon-inner\"><i class='fas fa-check'><\/i><\/div>\n               <\/div>\n                        <\/div>\n         <\/div>\n         \n                    <div  class=\"blox-boxed-small-square-icon-box-heading\">Why Sustainable Timber<\/div>\n                <\/div>\n  \n  \t\t  \n  \n                  <div class=\"blox-boxed-small-square-icon-box-content\">\n            <p>Learn how sustainable timber contributes to environmental protection, responsible sourcing, and long-term sustainability.<\/p>\n          <\/div>\n          \n  \t\t        \n          \n  \t\t\n  \t\t  \n<\/div>\n<!-- end Icon Box -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5912d30 elementor-widget elementor-widget-ucaddon_square_icon_box\" data-id=\"5912d30\" data-element_type=\"widget\" data-widget_type=\"ucaddon_square_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Icon Box -->\n\n<style>\/* widget: Icon Box *\/\n\n#uc_square_icon_box_elementor_5912d30 * { \n\tbox-sizing: border-box; \n}\n\n#uc_square_icon_box_elementor_5912d30{\n  font-family: inherit;\n  position:relative;\n}\n#uc_square_icon_box_elementor_5912d30 svg{\n  width:1em;\n  height:1em;\n}\n\n#uc_square_icon_box_elementor_5912d30 .blox-boxed-small-square-icon-box-icon{\n\tposition:relative;\n    display:flex;\n    justify-content:center;\n    align-items:center;\n    transform:rotate(0deg);\n    z-index:2;\n}\n#uc_square_icon_box_elementor_5912d30 .ue-icon {\n  display:inline-block;\n}\n#uc_square_icon_box_elementor_5912d30 .blox-boxed-small-square-icon-box-icon > div{\n\tposition:relative;\n    display:flex;\n    justify-content:center;\n    align-items:center;\n}\n#uc_square_icon_box_elementor_5912d30 .ue-icon-inner{\n    line-height:1em;\n\t} \t\n\n\n#uc_square_icon_box_elementor_5912d30 .ue-icon-inner svg{\n    height:1em;\n    width:1em;\n\t} \t\n\t\n.blox-boxed-small-square-icon-box-heading{\n\tfont-size:21px;\n\t}\n\n\n#uc_square_icon_box_elementor_5912d30:hover\n{\n  position:relative;\n  z-index:1;\n}\n\n\n#uc_square_icon_box_elementor_5912d30 .ue-title-separator span\n{\n  display:inline-block;\n}\n\n\n\n\n<\/style>\n\n<div class=\"square_icon_box\" id=\"uc_square_icon_box_elementor_5912d30\">\n  \n  \t   <div class=\"ue-icon-title-wrap\">\n                  <div class=\"ue-icon-wrap\">\n           <div class=\"ue-icon\">\n                            <div class=\"blox-boxed-small-square-icon-box-icon\">\n                 <div class=\"ue-icon-inner\"><i class='fas fa-check'><\/i><\/div>\n               <\/div>\n                        <\/div>\n         <\/div>\n         \n                    <div  class=\"blox-boxed-small-square-icon-box-heading\">Our Impact and Facts vs Myths<\/div>\n                <\/div>\n  \n  \t\t  \n  \n                  <div class=\"blox-boxed-small-square-icon-box-content\">\n            <p>Understand the real-world impact of certification and clarify common misconceptions about timber and sustainability.<\/p>\n          <\/div>\n          \n  \t\t        \n          \n  \t\t\n  \t\t  \n<\/div>\n<!-- end Icon Box -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ed69df8 e-con-full e-flex e-con e-child\" data-id=\"ed69df8\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3f49853 e-con-full e-flex e-con e-child\" data-id=\"3f49853\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-856d779 elementor-widget elementor-widget-ucaddon_square_icon_box\" data-id=\"856d779\" data-element_type=\"widget\" data-widget_type=\"ucaddon_square_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Icon Box -->\n\n<style>\/* widget: Icon Box *\/\n\n#uc_square_icon_box_elementor_856d779 * { \n\tbox-sizing: border-box; \n}\n\n#uc_square_icon_box_elementor_856d779{\n  font-family: inherit;\n  position:relative;\n}\n#uc_square_icon_box_elementor_856d779 svg{\n  width:1em;\n  height:1em;\n}\n\n#uc_square_icon_box_elementor_856d779 .blox-boxed-small-square-icon-box-icon{\n\tposition:relative;\n    display:flex;\n    justify-content:center;\n    align-items:center;\n    transform:rotate(0deg);\n    z-index:2;\n}\n#uc_square_icon_box_elementor_856d779 .ue-icon {\n  display:inline-block;\n}\n#uc_square_icon_box_elementor_856d779 .blox-boxed-small-square-icon-box-icon > div{\n\tposition:relative;\n    display:flex;\n    justify-content:center;\n    align-items:center;\n}\n#uc_square_icon_box_elementor_856d779 .ue-icon-inner{\n    line-height:1em;\n\t} \t\n\n\n#uc_square_icon_box_elementor_856d779 .ue-icon-inner svg{\n    height:1em;\n    width:1em;\n\t} \t\n\t\n.blox-boxed-small-square-icon-box-heading{\n\tfont-size:21px;\n\t}\n\n\n#uc_square_icon_box_elementor_856d779:hover\n{\n  position:relative;\n  z-index:1;\n}\n\n\n#uc_square_icon_box_elementor_856d779 .ue-title-separator span\n{\n  display:inline-block;\n}\n\n\n\n\n<\/style>\n\n<div class=\"square_icon_box\" id=\"uc_square_icon_box_elementor_856d779\">\n  \n  \t   <div class=\"ue-icon-title-wrap\">\n                  <div class=\"ue-icon-wrap\">\n           <div class=\"ue-icon\">\n                            <div class=\"blox-boxed-small-square-icon-box-icon\">\n                 <div class=\"ue-icon-inner\"><i class='fas fa-trophy'><\/i><\/div>\n               <\/div>\n                        <\/div>\n         <\/div>\n         \n                    <div  class=\"blox-boxed-small-square-icon-box-heading\">ESG Champions<\/div>\n                <\/div>\n  \n  \t\t  \n  \n                  <div class=\"blox-boxed-small-square-icon-box-content\">\n            <p>Specifiers and procurement professionals responsible for selecting materials and suppliers, ensuring timber products meet certification standards, sustainability requirements, and responsible sourcing policies.<\/p>\n          <\/div>\n          \n  \t\t        \n          \n  \t\t\n  \t\t  \n<\/div>\n<!-- end Icon Box -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d4b5cd0 e-con-full e-flex e-con e-child\" data-id=\"d4b5cd0\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-9ad6369 e-grid e-con-full e-con e-child\" data-id=\"9ad6369\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-323d1a0 elementor-widget elementor-widget-ucaddon_square_icon_box\" data-id=\"323d1a0\" data-element_type=\"widget\" data-widget_type=\"ucaddon_square_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Icon Box -->\n\n<style>\/* widget: Icon Box *\/\n\n#uc_square_icon_box_elementor_323d1a0 * { \n\tbox-sizing: border-box; \n}\n\n#uc_square_icon_box_elementor_323d1a0{\n  font-family: inherit;\n  position:relative;\n}\n#uc_square_icon_box_elementor_323d1a0 svg{\n  width:1em;\n  height:1em;\n}\n\n#uc_square_icon_box_elementor_323d1a0 .blox-boxed-small-square-icon-box-icon{\n\tposition:relative;\n    display:flex;\n    justify-content:center;\n    align-items:center;\n    transform:rotate(0deg);\n    z-index:2;\n}\n#uc_square_icon_box_elementor_323d1a0 .ue-icon {\n  display:inline-block;\n}\n#uc_square_icon_box_elementor_323d1a0 .blox-boxed-small-square-icon-box-icon > div{\n\tposition:relative;\n    display:flex;\n    justify-content:center;\n    align-items:center;\n}\n#uc_square_icon_box_elementor_323d1a0 .ue-icon-inner{\n    line-height:1em;\n\t} \t\n\n\n#uc_square_icon_box_elementor_323d1a0 .ue-icon-inner svg{\n    height:1em;\n    width:1em;\n\t} \t\n\t\n.blox-boxed-small-square-icon-box-heading{\n\tfont-size:21px;\n\t}\n\n\n#uc_square_icon_box_elementor_323d1a0:hover\n{\n  position:relative;\n  z-index:1;\n}\n\n\n#uc_square_icon_box_elementor_323d1a0 .ue-title-separator span\n{\n  display:inline-block;\n}\n\n\n  #uc_square_icon_box_elementor_323d1a0 .ue_box_link_overlay{\n    position:absolute;\n    display:block;\n    top:0;\n    bottom:0; \n    right:0;\n    left:0;\n  }\n\n\n<\/style>\n\n<div class=\"square_icon_box\" id=\"uc_square_icon_box_elementor_323d1a0\">\n  \n  \t   <div class=\"ue-icon-title-wrap\">\n                  <div class=\"ue-icon-wrap\">\n           <div class=\"ue-icon\">\n             <a style=\"display:inline-block; text-decoration:none;\" href=\"\/bm\/find-certified-companies\/\" >               <div class=\"blox-boxed-small-square-icon-box-icon\">\n                 <div class=\"ue-icon-inner\"><i class='fas fa-check'><\/i><\/div>\n               <\/div>\n             <\/a>           <\/div>\n         <\/div>\n         \n                    <div  class=\"blox-boxed-small-square-icon-box-heading\">Find Certified Companies and Products<\/div>\n                <\/div>\n  \n  \t\t  \n  \n                  <div class=\"blox-boxed-small-square-icon-box-content\">\n            <p>Search and verify suppliers certified under MTCS and PEFC, ensuring their certification supports credible ESG reporting and responsible procurement.<\/p>\n          <\/div>\n          \n  \t\t        \n          \n  \t\t  \t\t<a href=\"\/bm\/find-certified-companies\/\" class=\"ue_box_link_overlay\" > <\/a>\n        \n  \t\t  \n<\/div>\n<!-- end Icon Box -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c1955a2 elementor-widget elementor-widget-ucaddon_square_icon_box\" data-id=\"c1955a2\" data-element_type=\"widget\" data-widget_type=\"ucaddon_square_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Icon Box -->\n\n<style>\/* widget: Icon Box *\/\n\n#uc_square_icon_box_elementor_c1955a2 * { \n\tbox-sizing: border-box; \n}\n\n#uc_square_icon_box_elementor_c1955a2{\n  font-family: inherit;\n  position:relative;\n}\n#uc_square_icon_box_elementor_c1955a2 svg{\n  width:1em;\n  height:1em;\n}\n\n#uc_square_icon_box_elementor_c1955a2 .blox-boxed-small-square-icon-box-icon{\n\tposition:relative;\n    display:flex;\n    justify-content:center;\n    align-items:center;\n    transform:rotate(0deg);\n    z-index:2;\n}\n#uc_square_icon_box_elementor_c1955a2 .ue-icon {\n  display:inline-block;\n}\n#uc_square_icon_box_elementor_c1955a2 .blox-boxed-small-square-icon-box-icon > div{\n\tposition:relative;\n    display:flex;\n    justify-content:center;\n    align-items:center;\n}\n#uc_square_icon_box_elementor_c1955a2 .ue-icon-inner{\n    line-height:1em;\n\t} \t\n\n\n#uc_square_icon_box_elementor_c1955a2 .ue-icon-inner svg{\n    height:1em;\n    width:1em;\n\t} \t\n\t\n.blox-boxed-small-square-icon-box-heading{\n\tfont-size:21px;\n\t}\n\n\n#uc_square_icon_box_elementor_c1955a2:hover\n{\n  position:relative;\n  z-index:1;\n}\n\n\n#uc_square_icon_box_elementor_c1955a2 .ue-title-separator span\n{\n  display:inline-block;\n}\n\n\n\n\n<\/style>\n\n<div class=\"square_icon_box\" id=\"uc_square_icon_box_elementor_c1955a2\">\n  \n  \t   <div class=\"ue-icon-title-wrap\">\n                  <div class=\"ue-icon-wrap\">\n           <div class=\"ue-icon\">\n                            <div class=\"blox-boxed-small-square-icon-box-icon\">\n                 <div class=\"ue-icon-inner\"><i class='fas fa-check'><\/i><\/div>\n               <\/div>\n                        <\/div>\n         <\/div>\n         \n                    <div  class=\"blox-boxed-small-square-icon-box-heading\">Our Impact and Facts vs Myths<\/div>\n                <\/div>\n  \n  \t\t  \n  \n                  <div class=\"blox-boxed-small-square-icon-box-content\">\n            <p>Understand the measurable impact of certification and clarify common misconceptions about timber and sustainability.<\/p>\n          <\/div>\n          \n  \t\t        \n          \n  \t\t\n  \t\t  \n<\/div>\n<!-- end Icon Box -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b42f7f4 elementor-widget elementor-widget-ucaddon_square_icon_box\" data-id=\"b42f7f4\" data-element_type=\"widget\" data-widget_type=\"ucaddon_square_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Icon Box -->\n\n<style>\/* widget: Icon Box *\/\n\n#uc_square_icon_box_elementor_b42f7f4 * { \n\tbox-sizing: border-box; \n}\n\n#uc_square_icon_box_elementor_b42f7f4{\n  font-family: inherit;\n  position:relative;\n}\n#uc_square_icon_box_elementor_b42f7f4 svg{\n  width:1em;\n  height:1em;\n}\n\n#uc_square_icon_box_elementor_b42f7f4 .blox-boxed-small-square-icon-box-icon{\n\tposition:relative;\n    display:flex;\n    justify-content:center;\n    align-items:center;\n    transform:rotate(0deg);\n    z-index:2;\n}\n#uc_square_icon_box_elementor_b42f7f4 .ue-icon {\n  display:inline-block;\n}\n#uc_square_icon_box_elementor_b42f7f4 .blox-boxed-small-square-icon-box-icon > div{\n\tposition:relative;\n    display:flex;\n    justify-content:center;\n    align-items:center;\n}\n#uc_square_icon_box_elementor_b42f7f4 .ue-icon-inner{\n    line-height:1em;\n\t} \t\n\n\n#uc_square_icon_box_elementor_b42f7f4 .ue-icon-inner svg{\n    height:1em;\n    width:1em;\n\t} \t\n\t\n.blox-boxed-small-square-icon-box-heading{\n\tfont-size:21px;\n\t}\n\n\n#uc_square_icon_box_elementor_b42f7f4:hover\n{\n  position:relative;\n  z-index:1;\n}\n\n\n#uc_square_icon_box_elementor_b42f7f4 .ue-title-separator span\n{\n  display:inline-block;\n}\n\n\n\n\n<\/style>\n\n<div class=\"square_icon_box\" id=\"uc_square_icon_box_elementor_b42f7f4\">\n  \n  \t   <div class=\"ue-icon-title-wrap\">\n                  <div class=\"ue-icon-wrap\">\n           <div class=\"ue-icon\">\n                            <div class=\"blox-boxed-small-square-icon-box-icon\">\n                 <div class=\"ue-icon-inner\"><i class='fas fa-check'><\/i><\/div>\n               <\/div>\n                        <\/div>\n         <\/div>\n         \n                    <div  class=\"blox-boxed-small-square-icon-box-heading\">Why Sustainable Timber<\/div>\n                <\/div>\n  \n  \t\t  \n  \n                  <div class=\"blox-boxed-small-square-icon-box-content\">\n            <p>Learn how certified timber supports sustainability goals, protects forest ecosystems, and strengthens ESG performance.<\/p>\n          <\/div>\n          \n  \t\t        \n          \n  \t\t\n  \t\t  \n<\/div>\n<!-- end Icon Box -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-855ce68 elementor-widget elementor-widget-ucaddon_square_icon_box\" data-id=\"855ce68\" data-element_type=\"widget\" data-widget_type=\"ucaddon_square_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Icon Box -->\n\n<style>\/* widget: Icon Box *\/\n\n#uc_square_icon_box_elementor_855ce68 * { \n\tbox-sizing: border-box; \n}\n\n#uc_square_icon_box_elementor_855ce68{\n  font-family: inherit;\n  position:relative;\n}\n#uc_square_icon_box_elementor_855ce68 svg{\n  width:1em;\n  height:1em;\n}\n\n#uc_square_icon_box_elementor_855ce68 .blox-boxed-small-square-icon-box-icon{\n\tposition:relative;\n    display:flex;\n    justify-content:center;\n    align-items:center;\n    transform:rotate(0deg);\n    z-index:2;\n}\n#uc_square_icon_box_elementor_855ce68 .ue-icon {\n  display:inline-block;\n}\n#uc_square_icon_box_elementor_855ce68 .blox-boxed-small-square-icon-box-icon > div{\n\tposition:relative;\n    display:flex;\n    justify-content:center;\n    align-items:center;\n}\n#uc_square_icon_box_elementor_855ce68 .ue-icon-inner{\n    line-height:1em;\n\t} \t\n\n\n#uc_square_icon_box_elementor_855ce68 .ue-icon-inner svg{\n    height:1em;\n    width:1em;\n\t} \t\n\t\n.blox-boxed-small-square-icon-box-heading{\n\tfont-size:21px;\n\t}\n\n\n#uc_square_icon_box_elementor_855ce68:hover\n{\n  position:relative;\n  z-index:1;\n}\n\n\n#uc_square_icon_box_elementor_855ce68 .ue-title-separator span\n{\n  display:inline-block;\n}\n\n\n\n\n<\/style>\n\n<div class=\"square_icon_box\" id=\"uc_square_icon_box_elementor_855ce68\">\n  \n  \t   <div class=\"ue-icon-title-wrap\">\n                  <div class=\"ue-icon-wrap\">\n           <div class=\"ue-icon\">\n                            <div class=\"blox-boxed-small-square-icon-box-icon\">\n                 <div class=\"ue-icon-inner\"><i class='fas fa-check'><\/i><\/div>\n               <\/div>\n                        <\/div>\n         <\/div>\n         \n                    <div  class=\"blox-boxed-small-square-icon-box-heading\">ESG Compliance Playbook and Resources<\/div>\n                <\/div>\n  \n  \t\t  \n  \n                  <div class=\"blox-boxed-small-square-icon-box-content\">\n            <p>Download ESG guidance, playbooks, and supporting documents to help integrate certified timber into your ESG reporting and sustainability frameworks.<\/p>\n          <\/div>\n          \n  \t\t        \n          \n  \t\t\n  \t\t  \n<\/div>\n<!-- end Icon Box -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d1d20f4 elementor-widget elementor-widget-ucaddon_square_icon_box\" data-id=\"d1d20f4\" data-element_type=\"widget\" data-widget_type=\"ucaddon_square_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<!-- start Icon Box -->\n\n<style>\/* widget: Icon Box *\/\n\n#uc_square_icon_box_elementor_d1d20f4 * { \n\tbox-sizing: border-box; \n}\n\n#uc_square_icon_box_elementor_d1d20f4{\n  font-family: inherit;\n  position:relative;\n}\n#uc_square_icon_box_elementor_d1d20f4 svg{\n  width:1em;\n  height:1em;\n}\n\n#uc_square_icon_box_elementor_d1d20f4 .blox-boxed-small-square-icon-box-icon{\n\tposition:relative;\n    display:flex;\n    justify-content:center;\n    align-items:center;\n    transform:rotate(0deg);\n    z-index:2;\n}\n#uc_square_icon_box_elementor_d1d20f4 .ue-icon {\n  display:inline-block;\n}\n#uc_square_icon_box_elementor_d1d20f4 .blox-boxed-small-square-icon-box-icon > div{\n\tposition:relative;\n    display:flex;\n    justify-content:center;\n    align-items:center;\n}\n#uc_square_icon_box_elementor_d1d20f4 .ue-icon-inner{\n    line-height:1em;\n\t} \t\n\n\n#uc_square_icon_box_elementor_d1d20f4 .ue-icon-inner svg{\n    height:1em;\n    width:1em;\n\t} \t\n\t\n.blox-boxed-small-square-icon-box-heading{\n\tfont-size:21px;\n\t}\n\n\n#uc_square_icon_box_elementor_d1d20f4:hover\n{\n  position:relative;\n  z-index:1;\n}\n\n\n#uc_square_icon_box_elementor_d1d20f4 .ue-title-separator span\n{\n  display:inline-block;\n}\n\n\n  #uc_square_icon_box_elementor_d1d20f4 .ue_box_link_overlay{\n    position:absolute;\n    display:block;\n    top:0;\n    bottom:0; \n    right:0;\n    left:0;\n  }\n\n\n<\/style>\n\n<div class=\"square_icon_box\" id=\"uc_square_icon_box_elementor_d1d20f4\">\n  \n  \t   <div class=\"ue-icon-title-wrap\">\n                  <div class=\"ue-icon-wrap\">\n           <div class=\"ue-icon\">\n             <a style=\"display:inline-block; text-decoration:none;\" href=\"\/bm\/certified-forests-in-malaysia\/\" >               <div class=\"blox-boxed-small-square-icon-box-icon\">\n                 <div class=\"ue-icon-inner\"><i class='fas fa-check'><\/i><\/div>\n               <\/div>\n             <\/a>           <\/div>\n         <\/div>\n         \n                    <div  class=\"blox-boxed-small-square-icon-box-heading\">Certification Statistics Dashboard and Forest Map<\/div>\n                <\/div>\n  \n  \t\t  \n  \n                  <div class=\"blox-boxed-small-square-icon-box-content\">\n            <p>View certified companies, certification coverage, and explore certified forest areas across Malaysia.<\/p>\n          <\/div>\n          \n  \t\t        \n          \n  \t\t  \t\t<a href=\"\/bm\/certified-forests-in-malaysia\/\" class=\"ue_box_link_overlay\" > <\/a>\n        \n  \t\t  \n<\/div>\n<!-- end Icon Box -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>As a Business Organisation Access the standards, tools, and information needed by forest managers, auditors, and certification stakeholders involved in the MTCS. As A Business Organisation Industries and Businesses Industries and businesses involved in producing, processing, trading, or using timber products, seeking certification to demonstrate responsible sourcing and sustainability compliance. How to Get Certified Learn [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-3352","page","type-page","status-publish","hentry"],"blocksy_meta":{"has_hero_section":"disabled","vertical_spacing_source":"custom","content_area_spacing":"none","styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":6}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>As a Business Organisation - MTCC | MALAYSIAN TIMBER CERTIFICATION COUNCIL<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mtcc.com.my\/bm\/as-a-business-organisation\/\" \/>\n<meta property=\"og:locale\" content=\"ms_MY\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"As a Business Organisation - MTCC | MALAYSIAN TIMBER CERTIFICATION COUNCIL\" \/>\n<meta property=\"og:description\" content=\"As a Business Organisation Access the standards, tools, and information needed by forest managers, auditors, and certification stakeholders involved in the MTCS. As A Business Organisation Industries and Businesses Industries and businesses involved in producing, processing, trading, or using timber products, seeking certification to demonstrate responsible sourcing and sustainability compliance. How to Get Certified Learn [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mtcc.com.my\/bm\/as-a-business-organisation\/\" \/>\n<meta property=\"og:site_name\" content=\"MTCC | MALAYSIAN TIMBER CERTIFICATION COUNCIL\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-01T10:35:28+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minit\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mtcc.com.my\\\/as-a-business-organisation\\\/\",\"url\":\"https:\\\/\\\/mtcc.com.my\\\/as-a-business-organisation\\\/\",\"name\":\"As a Business Organisation - MTCC | MALAYSIAN TIMBER CERTIFICATION COUNCIL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mtcc.com.my\\\/#website\"},\"datePublished\":\"2026-03-16T06:41:07+00:00\",\"dateModified\":\"2026-07-01T10:35:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mtcc.com.my\\\/as-a-business-organisation\\\/#breadcrumb\"},\"inLanguage\":\"ms-MY\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mtcc.com.my\\\/as-a-business-organisation\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mtcc.com.my\\\/as-a-business-organisation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mtcc.com.my\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"As a Business Organisation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mtcc.com.my\\\/#website\",\"url\":\"https:\\\/\\\/mtcc.com.my\\\/\",\"name\":\"MTCC | MALAYSIAN TIMBER CERTIFICATION COUNCIL\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/mtcc.com.my\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mtcc.com.my\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ms-MY\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mtcc.com.my\\\/#organization\",\"name\":\"MTCC | MALAYSIAN TIMBER CERTIFICATION COUNCIL\",\"url\":\"https:\\\/\\\/mtcc.com.my\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ms-MY\",\"@id\":\"https:\\\/\\\/mtcc.com.my\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mtcc.com.my\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/main-logo-n.png\",\"contentUrl\":\"https:\\\/\\\/mtcc.com.my\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/main-logo-n.png\",\"width\":235,\"height\":329,\"caption\":\"MTCC | MALAYSIAN TIMBER CERTIFICATION COUNCIL\"},\"image\":{\"@id\":\"https:\\\/\\\/mtcc.com.my\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"As a Business Organisation - MTCC | MALAYSIAN TIMBER CERTIFICATION COUNCIL","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mtcc.com.my\/bm\/as-a-business-organisation\/","og_locale":"ms_MY","og_type":"article","og_title":"As a Business Organisation - MTCC | MALAYSIAN TIMBER CERTIFICATION COUNCIL","og_description":"As a Business Organisation Access the standards, tools, and information needed by forest managers, auditors, and certification stakeholders involved in the MTCS. As A Business Organisation Industries and Businesses Industries and businesses involved in producing, processing, trading, or using timber products, seeking certification to demonstrate responsible sourcing and sustainability compliance. How to Get Certified Learn [&hellip;]","og_url":"https:\/\/mtcc.com.my\/bm\/as-a-business-organisation\/","og_site_name":"MTCC | MALAYSIAN TIMBER CERTIFICATION COUNCIL","article_modified_time":"2026-07-01T10:35:28+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minit"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mtcc.com.my\/as-a-business-organisation\/","url":"https:\/\/mtcc.com.my\/as-a-business-organisation\/","name":"As a Business Organisation - MTCC | MALAYSIAN TIMBER CERTIFICATION COUNCIL","isPartOf":{"@id":"https:\/\/mtcc.com.my\/#website"},"datePublished":"2026-03-16T06:41:07+00:00","dateModified":"2026-07-01T10:35:28+00:00","breadcrumb":{"@id":"https:\/\/mtcc.com.my\/as-a-business-organisation\/#breadcrumb"},"inLanguage":"ms-MY","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mtcc.com.my\/as-a-business-organisation\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mtcc.com.my\/as-a-business-organisation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mtcc.com.my\/"},{"@type":"ListItem","position":2,"name":"As a Business Organisation"}]},{"@type":"WebSite","@id":"https:\/\/mtcc.com.my\/#website","url":"https:\/\/mtcc.com.my\/","name":"MTCC | MALAYSIAN TIMBER CERTIFICATION COUNCIL","description":"","publisher":{"@id":"https:\/\/mtcc.com.my\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mtcc.com.my\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ms-MY"},{"@type":"Organization","@id":"https:\/\/mtcc.com.my\/#organization","name":"MTCC | MALAYSIAN TIMBER CERTIFICATION COUNCIL","url":"https:\/\/mtcc.com.my\/","logo":{"@type":"ImageObject","inLanguage":"ms-MY","@id":"https:\/\/mtcc.com.my\/#\/schema\/logo\/image\/","url":"https:\/\/mtcc.com.my\/wp-content\/uploads\/2026\/02\/main-logo-n.png","contentUrl":"https:\/\/mtcc.com.my\/wp-content\/uploads\/2026\/02\/main-logo-n.png","width":235,"height":329,"caption":"MTCC | MALAYSIAN TIMBER CERTIFICATION COUNCIL"},"image":{"@id":"https:\/\/mtcc.com.my\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mtcc.com.my\/bm\/wp-json\/wp\/v2\/pages\/3352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mtcc.com.my\/bm\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mtcc.com.my\/bm\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mtcc.com.my\/bm\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mtcc.com.my\/bm\/wp-json\/wp\/v2\/comments?post=3352"}],"version-history":[{"count":34,"href":"https:\/\/mtcc.com.my\/bm\/wp-json\/wp\/v2\/pages\/3352\/revisions"}],"predecessor-version":[{"id":26275,"href":"https:\/\/mtcc.com.my\/bm\/wp-json\/wp\/v2\/pages\/3352\/revisions\/26275"}],"wp:attachment":[{"href":"https:\/\/mtcc.com.my\/bm\/wp-json\/wp\/v2\/media?parent=3352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}